{"id":15330,"date":"2026-06-10T10:38:37","date_gmt":"2026-06-10T08:38:37","guid":{"rendered":"https:\/\/www.muzard-sarl.com\/?p=15330"},"modified":"2026-07-31T12:15:25","modified_gmt":"2026-07-31T10:15:25","slug":"nos-materiaux","status":"publish","type":"post","link":"https:\/\/www.muzard-sarl.com\/en\/nos-materiaux\/","title":{"rendered":"Chez Muzard SARL : Bois, Cornes et Autres Materiaux"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"15330\" class=\"elementor elementor-15330\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ed479c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ed479c1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4552512\" data-id=\"4552512\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11ead00 elementor-widget elementor-widget-heading\" data-id=\"11ead00\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos Bois<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f2f6d94 elementor-widget elementor-widget-spacer\" data-id=\"f2f6d94\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73f648c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73f648c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e6e967f\" data-id=\"e6e967f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0b1d8f4 elementor-widget elementor-widget-image\" data-id=\"0b1d8f4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amarante-250x300.png\" class=\"attachment-medium size-medium wp-image-15338\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amarante-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amarante-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amarante-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amarante-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amarante-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amarante-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amarante-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amarante.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7835c8a\" data-id=\"7835c8a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4bed30 elementor-widget elementor-widget-heading\" data-id=\"f4bed30\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Amaranth<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef8c84e elementor-widget elementor-widget-text-editor\" data-id=\"ef8c84e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le<strong> bois d\u2019amarante<\/strong> est un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">bois pr\u00e9cieux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> d\u2019une <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">grande long\u00e9vit\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">duret\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> issu d\u2019arbres d\u2019Am\u00e9rique du Sud du genre Peltogyne.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il est connu pour sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">couleur violet-pourpre vif<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> qui<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">qui \u00e9volue avec le temps vers des teintes plus sombres, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">rouges ou brune<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"><strong>s<\/strong> \u00e0 cause de son occidation et son exposition au soleil, mais cette \u00e9volution de la couleur est lente.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">L&rsquo;amarante peut \u00eatre utilis\u00e9 pour de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">nombreux projets<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> : sols, mobiliers, objets de d\u00e9coration, bijoux, couteaux&#8230;<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il est aussi appel\u00e9 \u201c<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">bois violet<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">\u201d, \u00e0 ne pas confondre avec le bois de violette.<\/span><\/p><p>\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8936195 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8936195\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5753e9c\" data-id=\"5753e9c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bacab02 elementor-widget elementor-widget-spacer\" data-id=\"bacab02\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cacb071 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cacb071\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0528b16\" data-id=\"0528b16\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06de86c elementor-widget elementor-widget-heading\" data-id=\"06de86c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Amboine<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91e0779 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"91e0779\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">L\u2019<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">Amboine<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> est un bois <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">rare <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">prestigieux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">, tr\u00e8s recherch\u00e9, \u00e0 la <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">densit\u00e9 <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">et la <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">duret\u00e9 <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">\u00e9lev\u00e9es.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Ce bois pr\u00e9sente de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">sublimes motifs<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">, presque comme des <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">petits tourbillons<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">, car il provient d\u2019<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">excroissances naturelles<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> de l\u2019arbre. Ses couleurs peuvent varier d\u2019un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">marron intense<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> \u00e0 des <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">bruns-dor\u00e9s clairs<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Sa densit\u00e9 en fait un bois <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">durable<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> et adapt\u00e9 aux <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">projets minutieux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> demandant beaucoup e pr\u00e9cision.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Il est surtout utilis\u00e9 pour la fabrication d\u2019objets d\u2019art, de couteaux<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">et parfois, de lames de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">marimba <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">(sorte de xylophone)<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6fddbe9\" data-id=\"6fddbe9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58a04f4 e-transform elementor-widget elementor-widget-image\" data-id=\"58a04f4\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect&quot;:&quot;transform&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"960\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amboine-853x1024.png\" class=\"attachment-large size-large wp-image-15394\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amboine-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amboine-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amboine-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amboine-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amboine-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amboine-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amboine-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amboine.png 900w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ee69f99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee69f99\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1622766\" data-id=\"1622766\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f426a1 elementor-widget elementor-widget-spacer\" data-id=\"2f426a1\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-48698e8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"48698e8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3d2bebe\" data-id=\"3d2bebe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d78edfd e-transform elementor-widget elementor-widget-image\" data-id=\"d78edfd\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect&quot;:&quot;transform&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"960\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amourette-853x1024.png\" class=\"attachment-large size-large wp-image-15339\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amourette-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amourette-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amourette-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amourette-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amourette-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amourette-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amourette-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-amourette.png 900w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-93e60fd\" data-id=\"93e60fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f1c6761 elementor-widget elementor-widget-heading\" data-id=\"f1c6761\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Amourette<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96a0f5a elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"96a0f5a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">L\u2019<strong>amourette<\/strong> est un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">bois exotique<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> d\u2019Am\u00e9rique du Sud tr\u00e8s dense, \u00e9galement connu sous le nom de lettre mouchet\u00e9e, ayant \u00e9t\u00e9 utilis\u00e9 pour la fabrication de caract\u00e8res d\u2019imprimerie.<\/span><\/p>\n<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il est reconnu pour sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">duret\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, son <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">grain fin<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et ses <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">nuances de couleurs<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> allant <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">d\u2019un brun clair \u00e0 un brun profond<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p>\n<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il est utilis\u00e9 depuis des si\u00e8cles pour son <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">apparence sophistiqu\u00e9e<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> dans la confection d\u2019instruments de musique de haute qualit\u00e9 et dans la fabrication de couteaux et autres objets pr\u00e9cieux comme des stylos.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-be29f94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"be29f94\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4b65ce4\" data-id=\"4b65ce4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-673cb86 elementor-widget elementor-widget-spacer\" data-id=\"673cb86\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d356ff8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d356ff8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8bcf585\" data-id=\"8bcf585\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77a1641 elementor-widget elementor-widget-heading\" data-id=\"77a1641\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bocote<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42113a2 elementor-widget elementor-widget-text-editor\" data-id=\"42113a2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Bocote <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">est un bois sud-Am\u00e9ricain de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">qualit\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">durable <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">densit\u00e9 moyenne<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">. Il provient d\u2019un arbre \u00e0 croissance rapide pouvant atteindre les 35 m\u00e8tres.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Ce bois est identifiable \u00e0 ses <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">couleurs brun-jaune clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> travers\u00e9es de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">stries brun fonc\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> dues \u00e0 son veinage.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Ce bois est utilis\u00e9 dans la construction de bateaux, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">en lutherie, en \u00e9b\u00e9nisterie et dans l\u2019artisanat d\u2019objets en bois comme dans la coutellerie.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d0d1e7d\" data-id=\"d0d1e7d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1a9263 e-transform elementor-widget elementor-widget-image\" data-id=\"c1a9263\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect&quot;:&quot;transform&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bocote-250x300.png\" class=\"attachment-medium size-medium wp-image-15340\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bocote-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bocote-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bocote-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bocote-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bocote-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bocote-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bocote-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bocote.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-224d774 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"224d774\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a6a93fd\" data-id=\"a6a93fd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f006b85 elementor-widget elementor-widget-spacer\" data-id=\"f006b85\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-75ba0ff elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"75ba0ff\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ba04042\" data-id=\"ba04042\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-072f39b e-transform elementor-widget elementor-widget-image\" data-id=\"072f39b\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect&quot;:&quot;transform&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"960\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-rose-853x1024.png\" class=\"attachment-large size-large wp-image-15341\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-rose-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-rose-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-rose-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-rose-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-rose-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-rose-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-rose-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-rose.png 900w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8bd9e79\" data-id=\"8bd9e79\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95594ca elementor-widget elementor-widget-heading\" data-id=\"95594ca\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pink Wood<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eff3fc8 elementor-widget elementor-widget-text-editor\" data-id=\"eff3fc8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le <strong>bois de rose<\/strong> est un bois <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">luxueux<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">issus d\u2019arbres du genre Dalbergia, d\u2019une <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">grande densit\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">robustesse<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Ce bois se reconnais \u00e0 son <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">veinage<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et ses<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\"> teintes <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">allant du<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\"> brun clair ou fonc\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> \u00e0 un charmant <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">rose subtil<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, lui donnant une apparence chaleureuse.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il peut \u00eatre utilis\u00e9 en \u00e9b\u00e9nisterie,<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">marqueterie et en coutellerie pour sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">r\u00e9sistance aux chocs<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, c\u2019est un bois <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">polyvalent<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">autre type d\u2019arbre <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">utilis\u00e9 en <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">parfumerie <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">porte le<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\"> m\u00eame surnom<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, bien qu\u2019ils ne soient pas de la m\u00eame famille.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab4fb01 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab4fb01\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-976bfc1\" data-id=\"976bfc1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0135c4b elementor-widget elementor-widget-spacer\" data-id=\"0135c4b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-87bb55a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"87bb55a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-504c604\" data-id=\"504c604\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c138145 elementor-widget elementor-widget-heading\" data-id=\"c138145\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Snakewood<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a2d7f4 elementor-widget elementor-widget-text-editor\" data-id=\"0a2d7f4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Snakewood<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> est un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">bois pr\u00e9cieux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, d\u2019une duret\u00e9 \u00e9lev\u00e9e,<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">venant d\u2019Am\u00e9rique du Sud, des <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">for\u00eats Guyanaises<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Son apparence est <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">unique<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, ses <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">couleurs contrast\u00e9es<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> varient du <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">dor\u00e9 clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> au <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">brun profond<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et donnent un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">aspect marbr\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> au bois. De plus il est recouvert de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">petites stries et taches plus claires<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> pouvant rappeler les <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">\u00e9cailles d\u2019un serpent<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Ce bois est tr\u00e8s utilis\u00e9 en coutellerie pour sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">beaut\u00e9 <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et sa tenue au <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">polissage<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4a2a2ee\" data-id=\"4a2a2ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3460d59 elementor-widget elementor-widget-image\" data-id=\"3460d59\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"960\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-serpent-853x1024.png\" class=\"attachment-large size-large wp-image-15506\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-serpent-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-serpent-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-serpent-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-serpent-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-serpent-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-serpent-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-serpent-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-serpent.png 900w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bfab401 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bfab401\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e5294da\" data-id=\"e5294da\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f50b697 elementor-widget elementor-widget-spacer\" data-id=\"f50b697\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3a6cd6f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3a6cd6f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2f51ec8\" data-id=\"2f51ec8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d95e3b elementor-widget elementor-widget-image\" data-id=\"9d95e3b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-violette-1-250x300.png\" class=\"attachment-medium size-medium wp-image-15343\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-violette-1-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-violette-1-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-violette-1-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-violette-1-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-violette-1-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-violette-1-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-violette-1-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-violette-1.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e428865\" data-id=\"e428865\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a9095b elementor-widget elementor-widget-heading\" data-id=\"4a9095b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Purple wood<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fb7f8d5 elementor-widget elementor-widget-text-editor\" data-id=\"fb7f8d5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le<strong> bois de violette<\/strong> est un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">bois exotique pr\u00e9cieux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> tr\u00e8s <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">dense<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> de la famille des Fabaceae, proche des palissandres.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Son <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">veinage<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> cr\u00e9e de sublimes <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">contrastes<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, passant de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">brun sombre<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> \u00e0 des <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">teintes violac\u00e9es<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, donnant au bois un effet presque <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">marbr\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il est utilis\u00e9 par les \u00e9b\u00e9nistes, les artisans comme les bijoutiers et les couteliers et par les luthiers.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il est surnomm\u00e9 \u201c<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">kingwood<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">\u201d en anglais, \u00e9tant <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">r\u00e9serv\u00e9 aux nobles et \u00e0 l\u2019aristocratie<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> aux 17e et 18e si\u00e8cles.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-99a32ac elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"99a32ac\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5355199\" data-id=\"5355199\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad7dcce elementor-widget elementor-widget-spacer\" data-id=\"ad7dcce\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c72529b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c72529b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-87d5d3b\" data-id=\"87d5d3b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b24070 elementor-widget elementor-widget-heading\" data-id=\"3b24070\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Birchwood<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-febb3b5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"febb3b5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">Le <strong>bouleau madr\u00e9<\/strong>, \u00e9galement appel\u00e9 bouleau de Car\u00e9lie, de Finlande ou de Norv\u00e8ge est un bois connu pour les <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">motifs de son veinage<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">Ce motif se cr\u00e9e lors du gel lors des mont\u00e9es de s\u00e8ve de l\u2019abre au printemps.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">Il est reconnu pour les <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">contrastes \u00e9lev\u00e9s<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\"> de ses <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">veines sombres<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\"> et de son <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">c\u0153ur<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">, qui lui donnent cet <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">aspect unique<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\"> tr\u00e8s recherch\u00e9 presque <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">semblable \u00e0 du marbre<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">C\u2019est un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">bois rare et pr\u00e9cieux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\"> d\u2019une grande <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">durabilit\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">, tr\u00e8s utilis\u00e9 en coutellerie et en \u00e9b\u00e9nisterie pour la cr\u00e9ation de pi\u00e8ces de luxe.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-88c0aa5\" data-id=\"88c0aa5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f5beb0 elementor-widget elementor-widget-image\" data-id=\"0f5beb0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bouleau-madre-250x300.png\" class=\"attachment-medium size-medium wp-image-15344\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bouleau-madre-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bouleau-madre-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bouleau-madre-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bouleau-madre-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bouleau-madre-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bouleau-madre-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bouleau-madre-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bouleau-madre.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-70ee626 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"70ee626\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-85cd177\" data-id=\"85cd177\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6b5365f elementor-widget elementor-widget-spacer\" data-id=\"6b5365f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d13a1f8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d13a1f8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-18e442d\" data-id=\"18e442d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8e4ea2b elementor-widget elementor-widget-image\" data-id=\"8e4ea2b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-loupe-de-cade-250x300.png\" class=\"attachment-medium size-medium wp-image-15395\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-loupe-de-cade-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-loupe-de-cade-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-loupe-de-cade-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-loupe-de-cade-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-loupe-de-cade-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-loupe-de-cade-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-loupe-de-cade-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-loupe-de-cade.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eb53982\" data-id=\"eb53982\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0927c61 elementor-widget elementor-widget-heading\" data-id=\"0927c61\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Cade wood<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f688b66 elementor-widget elementor-widget-text-editor\" data-id=\"f688b66\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">La <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">loupe de Cade <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">nous provient de la c\u00f4te m\u00e9diterran\u00e9enne, venant d\u2019un petit arbre des <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">garrigues<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> de la famille des <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">gen\u00e9vriers<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Ce bois est <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">parfum\u00e9 naturellement<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> d\u2019une <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">odeur agr\u00e9able<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: normal;\">De couleur g\u00e9n\u00e9ralement <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: normal;\">brun clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: normal;\">, il pr\u00e9sente une superposition de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: normal;\">petites taches sombres<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: normal;\"> et d\u2019un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: normal;\">beau<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: normal;\">veinage <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: normal;\">subtil.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: normal;\">Le bois de cade est utilis\u00e9 sous plusieurs formes pour ses <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: normal;\">nombreuses vertus<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: normal;\"> : huile essentielle, huile noire, antimites, encens, fabrication d\u2019objets d\u2019art et \u00e9b\u00e9nisterie. Il <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: normal;\">laisse toujours une bonne odeur dans les ateliers<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: normal;\">.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-700a470 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"700a470\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4c6e974\" data-id=\"4c6e974\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e4be33 elementor-widget elementor-widget-spacer\" data-id=\"5e4be33\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab40bab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab40bab\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0680609\" data-id=\"0680609\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09883b3 elementor-widget elementor-widget-heading\" data-id=\"09883b3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ch\u00eane<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1308ddc elementor-widget elementor-widget-text-editor\" data-id=\"1308ddc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Ch\u00eane <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">est un arbre \u00e0 bois dur tr\u00e8s r\u00e9pandu, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">durable <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\"> tr\u00e8s r\u00e9sistant<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> aux insectes et aux champignons.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il a une apparence <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">brun clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> \u00e0 brun fonc\u00e9, avec un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">grain tr\u00e8s variable<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, pouvant \u00eatre fin comme tr\u00e8s grossier. Des <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">fines stries<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> sont pr\u00e9sentes sur le long de sa surface.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">\u00c9tant un arbre tr\u00e8s r\u00e9pandu, il est <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">tr\u00e8s utilis\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, en particulier en Europe.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il est utilis\u00e9 en menuiserie, \u00e9b\u00e9nisterie, pour la fabrication de tonneaux, d\u2019ustensiles, la construction de charpente et<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">de bateaux.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9ef172b\" data-id=\"9ef172b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e511374 e-transform elementor-widget elementor-widget-image\" data-id=\"e511374\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect&quot;:&quot;transform&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-chene-250x300.png\" class=\"attachment-medium size-medium wp-image-15846\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-chene-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-chene-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-chene-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-chene-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-chene-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-chene-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-chene-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-chene.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34c8a96 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"34c8a96\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ce47527\" data-id=\"ce47527\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d20027 elementor-widget elementor-widget-spacer\" data-id=\"4d20027\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-bfcf717\" data-id=\"bfcf717\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f54df12 elementor-widget elementor-widget-spacer\" data-id=\"f54df12\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e95487 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e95487\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1bea8f5\" data-id=\"1bea8f5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9317fa elementor-widget elementor-widget-image\" data-id=\"e9317fa\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ebene-royal-1-250x300.png\" class=\"attachment-medium size-medium wp-image-15351\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ebene-royal-1-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ebene-royal-1-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ebene-royal-1-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ebene-royal-1-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ebene-royal-1-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ebene-royal-1-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ebene-royal-1-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ebene-royal-1.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ff5841b\" data-id=\"ff5841b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4eaae22 elementor-widget elementor-widget-heading\" data-id=\"4eaae22\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Royal Ebony<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-616d2d7 elementor-widget elementor-widget-text-editor\" data-id=\"616d2d7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">L\u2019<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">\u00e9b\u00e8ne royal<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> est un bois <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">rare <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">pr\u00e9cieux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, d\u2019une <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">densit\u00e9 \u00e9lev\u00e9e<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et d\u2019une <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">grande durabilit\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\"> duret\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Provenant g\u00e9n\u00e9ralement d\u2019<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Asie du sud-est<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, en particulier du<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\"> Laos<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, cet \u00e9b\u00e8ne est reconnaissable \u00e0 ses couleurs <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">brun clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">noir profond<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> tr\u00e8s contrast\u00e9es qui font de lui un bois <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">unique<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">prestigieux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Ce mat\u00e9riau est bien souvent r\u00e9serv\u00e9 aux <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">pi\u00e8ces d\u2019exception<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et \u00e0 l\u2019artisanat du luxe, coutellerie et objets d\u2019art.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4739c98 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4739c98\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-fa5452c\" data-id=\"fa5452c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-77606a9 elementor-widget elementor-widget-spacer\" data-id=\"77606a9\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e9b2100\" data-id=\"e9b2100\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0b31ed elementor-widget elementor-widget-spacer\" data-id=\"e0b31ed\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-82f4089 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"82f4089\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-20e33ac\" data-id=\"20e33ac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8642bd elementor-widget elementor-widget-heading\" data-id=\"e8642bd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Goyavier<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23d63e6 elementor-widget elementor-widget-text-editor\" data-id=\"23d63e6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Goyavier <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">est un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">bois exotique<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> souvent <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">\u00e9chauff\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">stabilis\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> pour le rendre plus <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">dense<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">solide <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">en conservant sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">beaut\u00e9 naturelle<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">C\u2019est un bois \u00e0 l\u2019<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">esth\u00e9tique unique<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> gr\u00e2ce \u00e0 son <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">veinage contrats\u00e9 <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">faisant apparaitre des petites formes <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">marron dor\u00e9 claires<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> sur sa surface, un peu semblables \u00e0 de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">petites \u00e9cailles<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Gr\u00e2ce \u00e0 la stabilisation, il est robuste et r\u00e9sitant \u00e0 l\u2019humidit\u00e9, faisant de ce bois un mat\u00e9riau utile en artisanat, pour la fabrication de bijoux ou de manches de couteau.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-48afce0\" data-id=\"48afce0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-62b2010 e-transform elementor-widget elementor-widget-image\" data-id=\"62b2010\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect&quot;:&quot;transform&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-goyavier-250x300.png\" class=\"attachment-medium size-medium wp-image-15634\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-goyavier-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-goyavier-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-goyavier-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-goyavier-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-goyavier-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-goyavier-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-goyavier-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-goyavier.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c7426e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c7426e5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2d740fe\" data-id=\"2d740fe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f38f0c2 elementor-widget elementor-widget-spacer\" data-id=\"f38f0c2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ec1d57d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ec1d57d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-31b25fc\" data-id=\"31b25fc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d16d511 elementor-widget elementor-widget-image\" data-id=\"d16d511\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-hetre-echauffe-stabilise-250x300.png\" class=\"attachment-medium size-medium wp-image-15635\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-hetre-echauffe-stabilise-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-hetre-echauffe-stabilise-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-hetre-echauffe-stabilise-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-hetre-echauffe-stabilise-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-hetre-echauffe-stabilise-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-hetre-echauffe-stabilise-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-hetre-echauffe-stabilise-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-hetre-echauffe-stabilise.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a5fa1c0\" data-id=\"a5fa1c0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b13351c elementor-widget elementor-widget-heading\" data-id=\"b13351c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">H\u00eatre<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-52e6c67 elementor-widget elementor-widget-text-editor\" data-id=\"52e6c67\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">H\u00eatre <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">est un bois provenant d\u2019<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Europe<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> au <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">grain fin<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, souvent <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">\u00e9chauff\u00e9 et stabilis\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> pour le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">renforcer<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et le rendre <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">plus dense<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et plus <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">facile \u00e0 entretenir<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">La stabilisation ne modifie pas ses <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">couleurs naturelles<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, il pr\u00e9sente un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">veinage tr\u00e8s contrats\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, d\u00e9corant sa surface de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">fins motifs presque noirs<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> sur un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">fond brun vif clair mouchet\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le bois du h\u00eatre a de multiples usages, il peut \u00eatre utilis\u00e9 pour la fabrication de petits objets, de meubles, comme combustibles et ses fibres sont utilis\u00e9es en papeterie.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-268fac6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"268fac6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1a3b4d1\" data-id=\"1a3b4d1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4790e8d elementor-widget elementor-widget-spacer\" data-id=\"4790e8d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-28495df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"28495df\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a3eb9f1\" data-id=\"a3eb9f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecc8d22 elementor-widget elementor-widget-heading\" data-id=\"ecc8d22\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Olive wood<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88aa3a7 elementor-widget elementor-widget-text-editor\" data-id=\"88aa3a7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">L\u2019<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Olive wood<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> est un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">bois noble<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> tr\u00e8s <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">dense<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">dur <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">r\u00e9sistant<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, reconnu pour sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">durabilit\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">. Il est <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">peu poreux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et donc bien r\u00e9sistant \u00e0 l\u2019eau et aux bact\u00e9ries.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">D\u2019apparence <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">marron-dor\u00e9 clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, sa ronce est travers\u00e9e de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">veines plus sombres<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> lui donnant un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">aspect marbr\u00e9 sublime<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Sa duret\u00e9 en fait un bois tr\u00e8s utilis\u00e9 dans la menuiserie, la fabrication d\u2019ustensiles divers, l\u2019artisanat d\u2019objets d\u2019art et de d\u00e9coration, et m\u00eame comme b\u00e2ton taill\u00e9 \u00e0 macher pour les chiens.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9e3c86b\" data-id=\"9e3c86b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e120953 e-transform elementor-widget elementor-widget-image\" data-id=\"e120953\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect&quot;:&quot;transform&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-olivier-250x300.png\" class=\"attachment-medium size-medium wp-image-15847\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-olivier-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-olivier-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-olivier-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-olivier-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-olivier-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-olivier-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-olivier-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-olivier.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-bb705d5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"bb705d5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-68a2004\" data-id=\"68a2004\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-715582a elementor-widget elementor-widget-spacer\" data-id=\"715582a\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-22e32fb\" data-id=\"22e32fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-848c4f4 elementor-widget elementor-widget-spacer\" data-id=\"848c4f4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a968623 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a968623\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8e5ee3d\" data-id=\"8e5ee3d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6c97106 elementor-widget elementor-widget-image\" data-id=\"6c97106\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-250x300.png\" class=\"attachment-medium size-medium wp-image-15548\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cd160ac\" data-id=\"cd160ac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a76541 elementor-widget elementor-widget-heading\" data-id=\"2a76541\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bois de Fer<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a2f6ee0 elementor-widget elementor-widget-text-editor\" data-id=\"a2f6ee0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">Bois de Fer d\u2019Arizona<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> est l\u2019un des bois les <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">plus denses<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> et \u00e0 la <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">duret\u00e9 la plus \u00e9lev\u00e9e<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> qui existent.<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">L\u2019arbre dont il provient gagne cette r\u00e9sistance en poussant lentement dans des conditions extr\u00eames.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Il est <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">grandement appr\u00e9ci\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> pour ses couleurs <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">brunes vives presque violac\u00e9es<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">, ses <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">motifs <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">et son <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">veinage <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">contrast\u00e9s sublimes facilement reconnaissables.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Il est utilis\u00e9 dans la menuiserie et la fabrication d\u2019objets artisanaux, dont les manches de couteaux.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e924f3e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e924f3e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ebdc74c\" data-id=\"ebdc74c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6d66ed elementor-widget elementor-widget-spacer\" data-id=\"e6d66ed\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9b72204\" data-id=\"9b72204\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0229b5c elementor-widget elementor-widget-spacer\" data-id=\"0229b5c\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5da42b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5da42b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-db04284\" data-id=\"db04284\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d666310 elementor-widget elementor-widget-heading\" data-id=\"d666310\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Palmier - Rouge &amp; Noir<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb9ba38 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"eb9ba38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">bois de Palmier<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> est un mat\u00e9riaux <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">l\u00e9ger<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">durable <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">souple <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">particulier car il est constitu\u00e9 de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">fibres imbriqu\u00e9es<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le palmier n\u2019est pas vraiment un arbre mais une <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">plante arborescente<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> qui ne s\u2019\u00e9paissit jamais en vieillissant.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Ses fibres cr\u00e9ent de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">sublimes motifs<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> fins et contrast\u00e9s sur son bois, allant de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">brun clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> \u00e0 <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">marron sombre voir noir<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, en passant par des teintes <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">rouges<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il est utilis\u00e9 pour la fabrication de meubles, des bijoux, des couteaux et divers autres petits objets du quotidien ou de d\u00e9coration.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-19f1857\" data-id=\"19f1857\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9e5931 elementor-widget elementor-widget-image\" data-id=\"f9e5931\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-palmier-250x300.png\" class=\"attachment-medium size-medium wp-image-15346\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-palmier-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-palmier-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-palmier-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-palmier-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-palmier-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-palmier-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-palmier-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-palmier.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2c8055d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2c8055d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-678a13d\" data-id=\"678a13d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d317ba2 elementor-widget elementor-widget-spacer\" data-id=\"d317ba2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e01e31d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e01e31d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1e2974b\" data-id=\"1e2974b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8c5de0 elementor-widget elementor-widget-image\" data-id=\"f8c5de0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-pistachier-250x300.png\" class=\"attachment-medium size-medium wp-image-15508\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-pistachier-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-pistachier-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-pistachier-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-pistachier-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-pistachier-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-pistachier-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-pistachier-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-pistachier.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0821c11\" data-id=\"0821c11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e54b190 elementor-widget elementor-widget-heading\" data-id=\"e54b190\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pistachio<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93fd951 elementor-widget elementor-widget-text-editor\" data-id=\"93fd951\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Pistachio <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">est un bois de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">densit\u00e9 moyenne<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">,<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">stable<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">dur<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">r\u00e9sistant<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il a un aspect naturel <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">attrayant<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">\u00e9l\u00e9gant <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">gr\u00e2ce \u00e0 ses couleurs qui peuvent varier du <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">brun clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, au <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">vert clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, au <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">marron fonc\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, avec un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">veinage distinctif<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Son <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">apparence<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">texture fine<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et sa<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\"> r\u00e9sistance aux fissures et \u00e0 l\u2019humidit\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> en font un bois souvent utilis\u00e9 pour la sculpture.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Nous le retrouvons \u00e9galement en \u00e9b\u00e9nisterie, en coutellerie, en bijouterie et pour la fabrication de petits objets.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a20f6ab elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a20f6ab\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3918ae8\" data-id=\"3918ae8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f83291e elementor-widget elementor-widget-spacer\" data-id=\"f83291e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0e309f9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0e309f9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-950118f\" data-id=\"950118f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2f53599 elementor-widget elementor-widget-heading\" data-id=\"2f53599\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Plane<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fa05d38 elementor-widget elementor-widget-text-editor\" data-id=\"fa05d38\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Plane <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">est un arbe dont le bois est <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">plut\u00f4t dur<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">ferme<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, tr\u00e8s facile \u00e0 travailler. C\u2019est un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">bois pr\u00e9cieux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">haute qualit\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">De couleur <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">brun clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, sa surface est orn\u00e9e de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">petites maillures l\u00e9g\u00e8rement plus fonc\u00e9es<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, lui donnant un tr\u00e8s bel aspect <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">mouchet\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> unique.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il est un arbre tr\u00e8s r\u00e9pendu comme arbre d\u2019ornement et d\u2019alignement car il supporte bien les conditions de vie en milieu urbain. Son bois est utilis\u00e9 dans la fabrication de meubles, de jouets et autres<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">petits objets.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-40d575e\" data-id=\"40d575e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-566e807 e-transform elementor-widget elementor-widget-image\" data-id=\"566e807\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect&quot;:&quot;transform&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-platane-250x300.png\" class=\"attachment-medium size-medium wp-image-15848\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-platane-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-platane-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-platane-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-platane-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-platane-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-platane-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-platane-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-platane.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e5cade1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e5cade1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad5cdad\" data-id=\"ad5cdad\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d33ab12 elementor-widget elementor-widget-spacer\" data-id=\"d33ab12\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ac2e050 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ac2e050\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-190398d\" data-id=\"190398d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b7a7ba e-transform elementor-widget elementor-widget-image\" data-id=\"4b7a7ba\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect&quot;:&quot;transform&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-redheart-250x300.png\" class=\"attachment-medium size-medium wp-image-15549\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-redheart-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-redheart-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-redheart-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-redheart-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-redheart-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-redheart-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-redheart-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-redheart.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a774daa\" data-id=\"a774daa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f53b60a elementor-widget elementor-widget-heading\" data-id=\"f53b60a\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Redheart<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cb527d elementor-widget elementor-widget-text-editor\" data-id=\"4cb527d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">Redheart <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">(c\u0153ur rouge) est un bois tr\u00e8s <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">durable <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">gr\u00e2ce \u00e0 sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">forte densit\u00e9 <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">et son poids, provenant d\u2019Am\u00e9rique centrale ou du Sud.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Il est reconnaissable<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">\u00e0 ses <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">couleurs vives<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> allant de<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">brun-rouge<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> \u00e0 de magnifiques <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">roses orang\u00e9s<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">.<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Ses couleurs peuvent ternir au fil du temps \u00e0 cause du soleil.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">C\u2019est un bois \u00e0 l<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">\u2019esth\u00e9tique unique<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">facile <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">agr\u00e9able \u00e0 travailler<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">, on le retrouve donc souvent en menuiserie, en \u00e9b\u00e9nisterie, dans la fabrication d\u2019objets artisanaux et de placages d\u00e9coratifs.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-21b5a41 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"21b5a41\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-048283a\" data-id=\"048283a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3092cf6 elementor-widget elementor-widget-spacer\" data-id=\"3092cf6\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7faef9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7faef9a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-efd34cd\" data-id=\"efd34cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c79df2 elementor-widget elementor-widget-heading\" data-id=\"5c79df2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Burr Walnut<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b01379f elementor-widget elementor-widget-text-editor\" data-id=\"b01379f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">La <strong>ronce de noyer<\/strong> est d\u00e9finie comme un bois \u00e0 <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">fibres enchevetr\u00e9es<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\"> se trouvant \u00e0 la base de l\u2019arbre, pr\u00e8s des racines.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">C\u2019est un bois souvent utilis\u00e9 pour son <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">veinage d\u00e9coratif et contrast\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\"> et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">ses reflets dor\u00e9s \u00e0 brun sombre<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">Tr\u00e8s <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">dense<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">, le bois de noyer est <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">robuste et stable<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">, le rendant parfait pour les <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: normal;\">r\u00e9alisations fines aux finitions pr\u00e9cises<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: normal;\">Gr\u00e2ce \u00e0 cela, c\u2019est un bois tr\u00e8s populaire en \u00e9benisterie, menuiserie, sculpture et en coutellerie.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-53b9edc\" data-id=\"53b9edc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fe85480 e-transform elementor-widget elementor-widget-image\" data-id=\"fe85480\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect&quot;:&quot;transform&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ronce-de-noyer-250x300.png\" class=\"attachment-medium size-medium wp-image-15347\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ronce-de-noyer-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ronce-de-noyer-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ronce-de-noyer-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ronce-de-noyer-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ronce-de-noyer-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ronce-de-noyer-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ronce-de-noyer-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-ronce-de-noyer.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f686f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f686f4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9109b85\" data-id=\"9109b85\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b9221e elementor-widget elementor-widget-spacer\" data-id=\"8b9221e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-23034e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"23034e5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f5ad512\" data-id=\"f5ad512\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e94415f elementor-widget elementor-widget-image\" data-id=\"e94415f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-tamarin-echauffe-stabilise-250x300.png\" class=\"attachment-medium size-medium wp-image-15636\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-tamarin-echauffe-stabilise-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-tamarin-echauffe-stabilise-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-tamarin-echauffe-stabilise-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-tamarin-echauffe-stabilise-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-tamarin-echauffe-stabilise-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-tamarin-echauffe-stabilise-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-tamarin-echauffe-stabilise-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-tamarin-echauffe-stabilise.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c84548a\" data-id=\"c84548a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8da81e elementor-widget elementor-widget-heading\" data-id=\"e8da81e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tamarin<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3decc84 elementor-widget elementor-widget-text-editor\" data-id=\"3decc84\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Tamarin <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">est un bois <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">tropical<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> des r\u00e9gions chaudes d\u2019<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Afrique<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et d\u2019<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Asie<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">. Il est <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">\u00e9chauff\u00e9 et stabilis\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> pour offrir une plus grande <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">robustesse <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">r\u00e9sistance<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> sans changer sont apparence.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">C\u2019est un bois <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">g\u00e9n\u00e9ralement brun cr\u00e8me<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, marqu\u00e9 par un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">veinage irr\u00e9gulier tr\u00e8s fonc\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, cr\u00e9ant de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">sublimes<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">motifs uniques<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il est utilis\u00e9 en construction navale, en \u00e9b\u00e9nisterie, pour la fabrication d\u2019objets aux finitions fines et pour la fabrication<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">de bardeaux.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c87f72c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c87f72c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-56c9b9c\" data-id=\"56c9b9c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-178706e elementor-widget elementor-widget-spacer\" data-id=\"178706e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e165ad9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e165ad9\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5c35c76\" data-id=\"5c35c76\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-381aace elementor-widget elementor-widget-heading\" data-id=\"381aace\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Thuja wood<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b27423d elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"b27423d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">Thuja wood <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">est un bois pr\u00e9cieux connu pour sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">haute durabilit\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> et sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">r\u00e9sistance<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> \u00e0 la <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">pourriture <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">et aux <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">chocs<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">. Il provient d\u2019un arbre surnomm\u00e9 \u201c<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">arbre de la vie<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">\u201d en Am\u00e9rique du nord.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">C\u2019est un bois aux <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">couleurs chaudes<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">, dont la loupe pr\u00e9sente de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">jolies petites taches brun sombre<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> et un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">veinage l\u00e9ger<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Ce mat\u00e9riau est utilis\u00e9 dans l\u2019\u00e9b\u00e9nisterie, la fabrication d\u2019objets pr\u00e9cieux, de coffres et de couteaux. Le Thuya est \u00e9galement utilis\u00e9 comme pare-vue en haies \u00e0 cause de son <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">feuillage p\u00e9renne<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> et pour son <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">huile essentielle<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1dc59e3\" data-id=\"1dc59e3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43b4e6f e-transform elementor-widget elementor-widget-image\" data-id=\"43b4e6f\" data-element_type=\"widget\" data-settings=\"{&quot;_transform_flipX_effect&quot;:&quot;transform&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-thuya-250x300.png\" class=\"attachment-medium size-medium wp-image-15396\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-thuya-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-thuya-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-thuya-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-thuya-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-thuya-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-thuya-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-thuya-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-thuya.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76df3a0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76df3a0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ffbf5cd\" data-id=\"ffbf5cd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3ff88b elementor-widget elementor-widget-spacer\" data-id=\"e3ff88b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-dc7b991 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"dc7b991\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d74b611\" data-id=\"d74b611\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2797d43 elementor-widget elementor-widget-image\" data-id=\"2797d43\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-1-250x300.png\" class=\"attachment-medium size-medium wp-image-15550\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-1-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-1-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-1-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-1-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-1-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-1-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-1-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-fer-1.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-625843a\" data-id=\"625843a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-256f503 elementor-widget elementor-widget-heading\" data-id=\"256f503\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tilleul<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-de31f42 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"de31f42\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">Tilleul <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">est un bois europ\u00e9en, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">tr\u00e8s l\u00e9ger <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">et \u00e0 la <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">densit\u00e9 peu \u00e9lev\u00e9e<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">, il est <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">stabilis\u00e9 <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">pour \u00eatre plus facile \u00e0 travailler et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">plus durable<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Ce bois est <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">g\u00e9n\u00e9ralement clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">, plut\u00f4t <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">marron cr\u00e8me<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">, mais sa loupe pr\u00e9sente des couleurs plus sombres comme des<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">bruns fonc\u00e9s<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">Sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">l\u00e9g\u00e8ret\u00e9 <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\">et sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: bold; font-style: normal; font-kerning: none;\">texture lisse et douce<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); caret-color: #835a44; --ys-xuq: none; font-weight: 400; font-style: normal; font-kerning: none;\"> en font un bois tr\u00e8s utilis\u00e9 dans la fabrication de meubles, d\u2019instruments de musique et de manches de couteaux.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42b69ba elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42b69ba\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb1d5d3\" data-id=\"cb1d5d3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59e516e elementor-widget elementor-widget-spacer\" data-id=\"59e516e\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d59210 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d59210\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b14ebb8\" data-id=\"b14ebb8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0b3fa9 elementor-widget elementor-widget-heading\" data-id=\"e0b3fa9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zebrano<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0204d7 elementor-widget elementor-widget-text-editor\" data-id=\"b0204d7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Zebrano<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, zebrawood ou zingana, est un bois d\u2019origine <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">Africaine <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">assez <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">dur <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">au <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">veinage <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">facilement reconnaissable.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">En effet, celui-ci donne au bois un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">aspect<\/span> <span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">z\u00e9br\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, d\u2019o\u00f9 son nom.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le bois est de couleur <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">jaune-brun clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> avec de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">longues rayures plus sombres<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">C\u2019est un bois <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">d\u00e9coratif<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, souvent utilis\u00e9 comme plaquage ou bien pour faire des meubles.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il est \u00e9galement utilis\u00e9 pour fabriquer des manches d\u2019outils, de couteaux, voire des guitares.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-190e3dd\" data-id=\"190e3dd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ecf4016 elementor-widget elementor-widget-image\" data-id=\"ecf4016\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-zebrano-250x300.png\" class=\"attachment-medium size-medium wp-image-15507\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-zebrano-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-zebrano-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-zebrano-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-zebrano-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-zebrano-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-zebrano-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-zebrano-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-zebrano.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b753681 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b753681\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5f1a9fb\" data-id=\"5f1a9fb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-80a0ed1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"80a0ed1\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-30d4441 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"30d4441\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9d53b8e\" data-id=\"9d53b8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-023c401 elementor-widget elementor-widget-heading\" data-id=\"023c401\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos Cornes<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d6603f elementor-widget elementor-widget-spacer\" data-id=\"8d6603f\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e7742b3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7742b3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-86b77f0\" data-id=\"86b77f0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a9ffd7 elementor-widget elementor-widget-image\" data-id=\"2a9ffd7\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-belier-250x300.png\" class=\"attachment-medium size-medium wp-image-15353\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-belier-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-belier-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-belier-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-belier-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-belier-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-belier-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-belier-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-belier.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-cb3d038\" data-id=\"cb3d038\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6331a35 elementor-widget elementor-widget-heading\" data-id=\"6331a35\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">B\u00e9lier<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-997f675 elementor-widget elementor-widget-text-editor\" data-id=\"997f675\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">La <strong>corne de b\u00e9lier<\/strong> est consid\u00e9r\u00e9e comme un <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">mat\u00e9riau pr\u00e9cieux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Compos\u00e9e majoritairement de k\u00e9ratine, elle devient plus <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">mall\u00e9able <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">chauff\u00e9e.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Toute la corne peut \u00eatre utilis\u00e9e : sa croute, son centre, sa pointe ; cela permet d\u2019y retrouver de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">multiples textures<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">motifs<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">nuances de couleurs<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">. Gr\u00e2ce \u00e0 ses nombreuses apparences, chaque pi\u00e8ce en corne de b\u00e9lier est <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">unique<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">C\u2019est un mat\u00e9riau <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">robuste et durable<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">; utilis\u00e9 en coutellerie, dans la fabrication de pi\u00e8ces d\u00e9coratives, artistiques ou de bijoux.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le b\u00e9lier es souvent repr\u00e9sent\u00e9 comme symbole de la force de la nature.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ba34b61 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ba34b61\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2f411e7\" data-id=\"2f411e7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6873074 elementor-widget elementor-widget-spacer\" data-id=\"6873074\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0d2f14b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0d2f14b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-ff3bb26\" data-id=\"ff3bb26\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9133c09 elementor-widget elementor-widget-heading\" data-id=\"9133c09\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Buffle<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62dd20b elementor-widget elementor-widget-text-editor\" data-id=\"62dd20b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">La <strong>corne de buffle<\/strong> est un mat\u00e9riau reconnu car elle est aussi <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">robuste<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> que l\u2019animal dont elle provient, mais \u00e9galement pour sa <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">beaut\u00e9 naturelle<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">En g\u00e9n\u00e9ral d\u2019une couleur <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">brun-gris sombre<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, elle peut avoir des <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">taches bien plus claires<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, ce qui cr\u00e9e de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">sublimes contrastes <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et un effet<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\"> marbr\u00e9.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Sa grande <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">durabilit\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> en fait un materiau populaire chez les artisans.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Elle est utilis\u00e9e pour la fabrication de manches de couteaux et de plaques pour meubles.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le buffle d\u2019Inde est aussi appel\u00e9 buffle d\u2019eau, venant de l\u2019anglais <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">\u201cwater buffalo\u201d.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-e62b7c2\" data-id=\"e62b7c2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61d5b06 elementor-widget elementor-widget-image\" data-id=\"61d5b06\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"960\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-buffle-853x1024.png\" class=\"attachment-large size-large wp-image-15355\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-buffle-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-buffle-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-buffle-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-buffle-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-buffle-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-buffle-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-buffle-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-buffle.png 900w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8bf5228 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8bf5228\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-63aa02d\" data-id=\"63aa02d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b145ba2 elementor-widget elementor-widget-spacer\" data-id=\"b145ba2\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6dcadd6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6dcadd6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-970c728\" data-id=\"970c728\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fc1354 elementor-widget elementor-widget-image\" data-id=\"6fc1354\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-zebu-250x300.png\" class=\"attachment-medium size-medium wp-image-15356\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-zebu-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-zebu-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-zebu-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-zebu-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-zebu-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-zebu-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-zebu-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-corne-de-zebu.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2fa50eb\" data-id=\"2fa50eb\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d0a56e0 elementor-widget elementor-widget-heading\" data-id=\"d0a56e0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Z\u00e9bu<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6303d94 elementor-widget elementor-widget-text-editor\" data-id=\"6303d94\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">La <strong>corne de z\u00e9bu<\/strong> est un mat\u00e9riau <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">robuste, r\u00e9sistant, durable et polyvalent<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Elle pr\u00e9sente une <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">vari\u00e9t\u00e9 de couleurs<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, d\u2019un blanc cr\u00e8me \u00e0 un brun profond, cr\u00e9ant des <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">motifs uniques<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et une tr\u00e8s belle esth\u00e9tique.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">C\u2019est un mat\u00e9riau <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">facile \u00e0 travailler et \u00e0 fa\u00e7onner<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> pour les artisans mais demandant quand m\u00eame une <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">grande pr\u00e9cision<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Elle est le plus souvent utilis\u00e9e en coutellerie et dans la cr\u00e9ation de pi\u00e8ces d\u00e9coratives.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le nom du z\u00e9bu vient du tib\u00e9tain \u201czeba\u201d signifiant \u201cbosse\u201d, car il poss\u00e8de une bosse sur son dos.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f471f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f471f3\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f0c4257\" data-id=\"f0c4257\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27956e0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"27956e0\" data-element_type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a58986e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a58986e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-de1dd80\" data-id=\"de1dd80\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab10eaf elementor-widget elementor-widget-heading\" data-id=\"ab10eaf\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nos Autres Mat\u00e9riaux<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-73a5b4d elementor-widget elementor-widget-spacer\" data-id=\"73a5b4d\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6734929 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6734929\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f44ef43\" data-id=\"f44ef43\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e3e8c9 elementor-widget elementor-widget-image\" data-id=\"5e3e8c9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"960\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-cerf-853x1024.png\" class=\"attachment-large size-large wp-image-15357\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-cerf-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-cerf-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-cerf-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-cerf-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-cerf-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-cerf-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-cerf-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-bois-de-cerf.png 900w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-495a073\" data-id=\"495a073\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c1db815 elementor-widget elementor-widget-heading\" data-id=\"c1db815\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Deer antler<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4b97a1 elementor-widget elementor-widget-text-editor\" data-id=\"c4b97a1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">bois de cerf<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> est un mat\u00e9riau <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">noble <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">rustique<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">robuste <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">l\u00e9ger <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">\u00e0 la densit\u00e9 assez variable.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il provient des <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">ramures <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">de cerf m\u00e2les, qui <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">tombent naturellement<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">repoussent <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">chaque ann\u00e9e.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">L\u2019ext\u00e9rieur du bois est d\u2019une couleur <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">brun fonc\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et l\u2019int\u00e9rieur peut \u00eatre de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">blanc cr\u00e8me<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> \u00e0\u00a0<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"font-size: 0.875rem; color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">marron-gris clair<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"font-size: 0.875rem; color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il est utilis\u00e9 pour la fabrication de couteaux, de stylos; de bijoux, de petites sculptures et objets d\u2019art.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0054516 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0054516\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74bf012\" data-id=\"74bf012\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23bbc01 elementor-widget elementor-widget-spacer\" data-id=\"23bbc01\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa6d8b6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa6d8b6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9af3e09\" data-id=\"9af3e09\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4b8d3d0 elementor-widget elementor-widget-heading\" data-id=\"4b8d3d0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Mammouth<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-584391a elementor-widget elementor-widget-text-editor\" data-id=\"584391a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">L\u2019<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">ivoire<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et la <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">molaire de mammouth<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> sont des mat\u00e9riaux surprenant, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">pr\u00e9cieux <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">rare<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, venant d\u2019un animal pr\u00e9historique, le <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">mammouth laineux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Ce sont des mat\u00e9riaux <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">denses <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">aux <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">textures uniques<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> et aux<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\"> couleurs vari\u00e9es<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, allant du <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">blanc cr\u00e8me<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> au <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">brun fonc\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, ayant parfois des <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">nuances vertes ou bleues<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Ce sont des mat\u00e9riaux utilis\u00e9s dans la coutellerie, l\u2019artisanat d\u2019objets d\u2019art et de bijoux, et \u00e9galement recherch\u00e9s par certains <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">collectionneurs<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Bien que <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">l\u00e9gal <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">\u00e0 la vente, ces mat\u00e9riaux restent soumis \u00e0 des <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">r\u00e8glementations<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1ae1969\" data-id=\"1ae1969\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f9916d elementor-widget elementor-widget-image\" data-id=\"7f9916d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-mammouth-ivoire-250x300.png\" class=\"attachment-medium size-medium wp-image-15358\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-mammouth-ivoire-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-mammouth-ivoire-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-mammouth-ivoire-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-mammouth-ivoire-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-mammouth-ivoire-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-mammouth-ivoire-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-mammouth-ivoire-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/bois-materiaux-mammouth-ivoire.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-64a2f6a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"64a2f6a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f2b67a\" data-id=\"8f2b67a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-718f65b elementor-widget elementor-widget-spacer\" data-id=\"718f65b\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c637697 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c637697\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-738dbb7\" data-id=\"738dbb7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ddcafe elementor-widget elementor-widget-image\" data-id=\"1ddcafe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"250\" height=\"300\" src=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/materiaux-os-de-chameau-250x300.png\" class=\"attachment-medium size-medium wp-image-15359\" alt=\"\" srcset=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/materiaux-os-de-chameau-250x300.png 250w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/materiaux-os-de-chameau-853x1024.png 853w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/materiaux-os-de-chameau-768x922.png 768w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/materiaux-os-de-chameau-10x12.png 10w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/materiaux-os-de-chameau-500x600.png 500w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/materiaux-os-de-chameau-800x960.png 800w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/materiaux-os-de-chameau-600x720.png 600w, https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/materiaux-os-de-chameau.png 900w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-907a560\" data-id=\"907a560\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1609577 elementor-widget elementor-widget-heading\" data-id=\"1609577\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Os de Chameau<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-95b5c67 elementor-widget elementor-widget-text-editor\" data-id=\"95b5c67\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">L\u2019<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">os de chameau<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> est un mat\u00e9riau <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">noble<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">robuste <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">et <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">r\u00e9sistant<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, appr\u00e9ci\u00e9 pour sa texture et sa capacit\u00e9 \u00e0 \u00eatre <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">stabilis\u00e9 et teint\u00e9<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Naturel, l\u2019os de chameau est <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">blanc<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, mais il peut \u00eatre teint\u00e9 de <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">multiples couleurs<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\"> : orange, bleu, rose, bicolore&#8230;<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Il peut \u00eatre <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">sculpt\u00e9 et poli<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, ce qui en fait un mat\u00e9riau parfait pour la cr\u00e9ation d\u2019objets d\u2019art, d\u2019objets d\u00e9coratifs et pour la coutellerie.<\/span><\/p><p><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">Le chameau est un animal reconnaissable \u00e0 ses <\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-weight: bold; font-kerning: none;\">deux bosses<\/span><span class=\"a_GcMg font-feature-liga-off font-feature-clig-off font-feature-calt-off text-decoration-none text-strikethrough-none\" style=\"color: rgba(131,90,68,var(--o42jjq,1)); --ys-xuq: none; font-kerning: none;\">, contrairement au dromadaire qui n\u2019en a qu\u2019une.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8e5d929 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8e5d929\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cc6077c\" data-id=\"cc6077c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ed834f4 elementor-widget elementor-widget-spacer\" data-id=\"ed834f4\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c28bfb7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c28bfb7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-57faa30\" data-id=\"57faa30\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fad298 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"8fad298\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.muzard-sarl.com\/en\/nos-materiaux-naturels\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">D\u00e9couvrez nos mat\u00e9riaux<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nos Bois Amarante Le bois d\u2019amarante est un bois pr\u00e9cieux d\u2019une grande long\u00e9vit\u00e9 et duret\u00e9 issu d\u2019arbres d\u2019Am\u00e9rique du Sud du genre Peltogyne. Il est connu pour sa couleur violet-pourpre &#8230;<\/p>","protected":false},"author":3,"featured_media":15335,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[]},"categories":[516],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Chez Muzard SARL : Bois, Cornes et Autres Materiaux - Muzard SARL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.muzard-sarl.com\/en\/nos-materiaux\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Chez Muzard SARL : Bois, Cornes et Autres Materiaux - Muzard SARL\" \/>\n<meta property=\"og:description\" content=\"Nos Bois Amarante Le bois d\u2019amarante est un bois pr\u00e9cieux d\u2019une grande long\u00e9vit\u00e9 et duret\u00e9 issu d\u2019arbres d\u2019Am\u00e9rique du Sud du genre Peltogyne. Il est connu pour sa couleur violet-pourpre ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.muzard-sarl.com\/en\/nos-materiaux\/\" \/>\n<meta property=\"og:site_name\" content=\"Muzard SARL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/muzardSarl\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-06-10T08:38:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-31T10:15:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/materiaux-bois-corne-os-mammouth.png\" \/>\n\t<meta property=\"og:image:width\" content=\"2240\" \/>\n\t<meta property=\"og:image:height\" content=\"1260\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maelle Muzard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maelle Muzard\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"19 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.muzard-sarl.com\/nos-materiaux\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/nos-materiaux\/\"},\"author\":{\"name\":\"Maelle Muzard\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#\/schema\/person\/bb2752e8c98b88b17341543bfdd92259\"},\"headline\":\"Chez Muzard SARL : Bois, Cornes et Autres Materiaux\",\"datePublished\":\"2026-06-10T08:38:37+00:00\",\"dateModified\":\"2026-07-31T10:15:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/nos-materiaux\/\"},\"wordCount\":2749,\"publisher\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#organization\"},\"articleSection\":[\"Pour tout conna\u00eetre\"],\"inLanguage\":\"en-GB\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.muzard-sarl.com\/nos-materiaux\/\",\"url\":\"https:\/\/www.muzard-sarl.com\/nos-materiaux\/\",\"name\":\"Chez Muzard SARL : Bois, Cornes et Autres Materiaux - Muzard SARL\",\"isPartOf\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#website\"},\"datePublished\":\"2026-06-10T08:38:37+00:00\",\"dateModified\":\"2026-07-31T10:15:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/nos-materiaux\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.muzard-sarl.com\/nos-materiaux\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.muzard-sarl.com\/nos-materiaux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.muzard-sarl.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chez Muzard SARL : Bois, Cornes et Autres Materiaux\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#website\",\"url\":\"https:\/\/www.muzard-sarl.com\/\",\"name\":\"Muzard SARL\",\"description\":\"Fabricant d&#039;objets en bois et corne depuis 1990\",\"publisher\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.muzard-sarl.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#organization\",\"name\":\"MUZARD SARL\",\"url\":\"https:\/\/www.muzard-sarl.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png\",\"contentUrl\":\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png\",\"width\":1916,\"height\":413,\"caption\":\"MUZARD SARL\"},\"image\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/muzardSarl\/\",\"https:\/\/www.instagram.com\/muzard_sarl\/?hl=fr\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#\/schema\/person\/bb2752e8c98b88b17341543bfdd92259\",\"name\":\"Maelle Muzard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/e5c1e6bddd782225359bce9be9108db4?s=96&d=retro&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/e5c1e6bddd782225359bce9be9108db4?s=96&d=retro&r=g\",\"caption\":\"Maelle Muzard\"},\"url\":\"https:\/\/www.muzard-sarl.com\/en\/author\/muzardsarl\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Chez Muzard SARL : Bois, Cornes et Autres Materiaux - Muzard SARL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.muzard-sarl.com\/en\/nos-materiaux\/","og_locale":"en_GB","og_type":"article","og_title":"Chez Muzard SARL : Bois, Cornes et Autres Materiaux - Muzard SARL","og_description":"Nos Bois Amarante Le bois d\u2019amarante est un bois pr\u00e9cieux d\u2019une grande long\u00e9vit\u00e9 et duret\u00e9 issu d\u2019arbres d\u2019Am\u00e9rique du Sud du genre Peltogyne. Il est connu pour sa couleur violet-pourpre ...","og_url":"https:\/\/www.muzard-sarl.com\/en\/nos-materiaux\/","og_site_name":"Muzard SARL","article_publisher":"https:\/\/www.facebook.com\/muzardSarl\/","article_published_time":"2026-06-10T08:38:37+00:00","article_modified_time":"2026-07-31T10:15:25+00:00","og_image":[{"width":2240,"height":1260,"url":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/materiaux-bois-corne-os-mammouth.png","type":"image\/png"}],"author":"Maelle Muzard","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Maelle Muzard","Estimated reading time":"19 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.muzard-sarl.com\/nos-materiaux\/#article","isPartOf":{"@id":"https:\/\/www.muzard-sarl.com\/nos-materiaux\/"},"author":{"name":"Maelle Muzard","@id":"https:\/\/www.muzard-sarl.com\/#\/schema\/person\/bb2752e8c98b88b17341543bfdd92259"},"headline":"Chez Muzard SARL : Bois, Cornes et Autres Materiaux","datePublished":"2026-06-10T08:38:37+00:00","dateModified":"2026-07-31T10:15:25+00:00","mainEntityOfPage":{"@id":"https:\/\/www.muzard-sarl.com\/nos-materiaux\/"},"wordCount":2749,"publisher":{"@id":"https:\/\/www.muzard-sarl.com\/#organization"},"articleSection":["Pour tout conna\u00eetre"],"inLanguage":"en-GB"},{"@type":"WebPage","@id":"https:\/\/www.muzard-sarl.com\/nos-materiaux\/","url":"https:\/\/www.muzard-sarl.com\/nos-materiaux\/","name":"Chez Muzard SARL : Bois, Cornes et Autres Materiaux - Muzard SARL","isPartOf":{"@id":"https:\/\/www.muzard-sarl.com\/#website"},"datePublished":"2026-06-10T08:38:37+00:00","dateModified":"2026-07-31T10:15:25+00:00","breadcrumb":{"@id":"https:\/\/www.muzard-sarl.com\/nos-materiaux\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.muzard-sarl.com\/nos-materiaux\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.muzard-sarl.com\/nos-materiaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.muzard-sarl.com\/"},{"@type":"ListItem","position":2,"name":"Chez Muzard SARL : Bois, Cornes et Autres Materiaux"}]},{"@type":"WebSite","@id":"https:\/\/www.muzard-sarl.com\/#website","url":"https:\/\/www.muzard-sarl.com\/","name":"Muzard SARL","description":"Manufacturer of wooden objects and horns since 1990","publisher":{"@id":"https:\/\/www.muzard-sarl.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.muzard-sarl.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.muzard-sarl.com\/#organization","name":"MUZARD SARL","url":"https:\/\/www.muzard-sarl.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png","contentUrl":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png","width":1916,"height":413,"caption":"MUZARD SARL"},"image":{"@id":"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/muzardSarl\/","https:\/\/www.instagram.com\/muzard_sarl\/?hl=fr"]},{"@type":"Person","@id":"https:\/\/www.muzard-sarl.com\/#\/schema\/person\/bb2752e8c98b88b17341543bfdd92259","name":"Maelle Muzard","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.muzard-sarl.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/e5c1e6bddd782225359bce9be9108db4?s=96&d=retro&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e5c1e6bddd782225359bce9be9108db4?s=96&d=retro&r=g","caption":"Maelle Muzard"},"url":"https:\/\/www.muzard-sarl.com\/en\/author\/muzardsarl\/"}]}},"jetpack_featured_media_url":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2026\/06\/materiaux-bois-corne-os-mammouth.png","_links":{"self":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/posts\/15330"}],"collection":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/comments?post=15330"}],"version-history":[{"count":51,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/posts\/15330\/revisions"}],"predecessor-version":[{"id":15851,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/posts\/15330\/revisions\/15851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/media\/15335"}],"wp:attachment":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/media?parent=15330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/categories?post=15330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/tags?post=15330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}