{"id":11074,"date":"2024-12-05T14:13:29","date_gmt":"2024-12-05T13:13:29","guid":{"rendered":"https:\/\/www.muzard-sarl.com\/?post_type=product&#038;p=11074"},"modified":"2025-01-27T12:20:06","modified_gmt":"2025-01-27T11:20:06","slug":"plaquettes-en-loupe-de-bois-de-cade-qualite-9","status":"publish","type":"product","link":"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/","title":{"rendered":"Plaquettes en Loupe de Bois de Cade Qualit\u00e9++"},"content":{"rendered":"<p>Paire de plaquettes en <strong>loupe de bois de cade<\/strong><\/p>\n<p>Bois provenant du Sud de la France, nous sommes en relation avec l&rsquo;ONF pour pouvoir travailler ce bois.<\/p>\n<p><strong>Produit exceptionnel<\/strong><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Dimensions : 130 x 35 x 7 mm<\/p>\n<p>&nbsp;<\/p>","protected":false},"featured_media":11535,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[]},"product_cat":[43,273],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plaquettes en Loupe de Bois de Cade Qualit\u00e9++ - Muzard SARL<\/title>\n<meta name=\"description\" content=\"Paire de plaquettes en bois de cade mixte. Id\u00e9al pour la fabrication de vos manches de couteaux. Vous serez surpris par le parfum de ce bois.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plaquettes en Loupe de Bois de Cade Qualit\u00e9++ - Muzard SARL\" \/>\n<meta property=\"og:description\" content=\"Paire de plaquettes en bois de cade mixte. Id\u00e9al pour la fabrication de vos manches de couteaux. Vous serez surpris par le parfum de ce bois.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/\" \/>\n<meta property=\"og:site_name\" content=\"Muzard SARL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/muzardSarl\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-27T11:20:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2024\/12\/plaquettes-loupe-de-cade.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/\",\"url\":\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/\",\"name\":\"Plaquettes en Loupe de Bois de Cade Qualit\u00e9++ - Muzard SARL\",\"isPartOf\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#website\"},\"datePublished\":\"2024-12-05T13:13:29+00:00\",\"dateModified\":\"2025-01-27T11:20:06+00:00\",\"description\":\"Paire de plaquettes en bois de cade mixte. Id\u00e9al pour la fabrication de vos manches de couteaux. Vous serez surpris par le parfum de ce bois.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.muzard-sarl.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique Mat\u00e9riaux de Coutellerie\",\"item\":\"https:\/\/www.muzard-sarl.com\/boutique-en-ligne-materiaux-metier-dart\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plaquettes et carrelets en Bois\",\"item\":\"https:\/\/www.muzard-sarl.com\/categorie-produit\/plaquettes-et-carrelets-en-bois\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Plaquettes en Loupe de Bois de Cade Qualit\u00e9++\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#website\",\"url\":\"https:\/\/www.muzard-sarl.com\/\",\"name\":\"Muzard SARL\",\"description\":\"Fabricant d&#039;objets en bois et corne depuis 1990\",\"publisher\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.muzard-sarl.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#organization\",\"name\":\"MUZARD SARL\",\"url\":\"https:\/\/www.muzard-sarl.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png\",\"contentUrl\":\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png\",\"width\":1916,\"height\":413,\"caption\":\"MUZARD SARL\"},\"image\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/muzardSarl\/\",\"https:\/\/www.instagram.com\/muzard_sarl\/?hl=fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plaquettes en Loupe de Bois de Cade Qualit\u00e9++ - Muzard SARL","description":"Paire de plaquettes en bois de cade mixte. Id\u00e9al pour la fabrication de vos manches de couteaux. Vous serez surpris par le parfum de ce bois.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/","og_locale":"en_GB","og_type":"article","og_title":"Plaquettes en Loupe de Bois de Cade Qualit\u00e9++ - Muzard SARL","og_description":"Paire de plaquettes en bois de cade mixte. Id\u00e9al pour la fabrication de vos manches de couteaux. Vous serez surpris par le parfum de ce bois.","og_url":"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/","og_site_name":"Muzard SARL","article_publisher":"https:\/\/www.facebook.com\/muzardSarl\/","article_modified_time":"2025-01-27T11:20:06+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2024\/12\/plaquettes-loupe-de-cade.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/","url":"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/","name":"Plaquettes en Loupe de Bois de Cade Qualit\u00e9++ - Muzard SARL","isPartOf":{"@id":"https:\/\/www.muzard-sarl.com\/#website"},"datePublished":"2024-12-05T13:13:29+00:00","dateModified":"2025-01-27T11:20:06+00:00","description":"Paire de plaquettes en bois de cade mixte. Id\u00e9al pour la fabrication de vos manches de couteaux. Vous serez surpris par le parfum de ce bois.","breadcrumb":{"@id":"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.muzard-sarl.com\/produit\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-en-loupe-de-bois-de-cade-qualite-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.muzard-sarl.com\/"},{"@type":"ListItem","position":2,"name":"Boutique Mat\u00e9riaux de Coutellerie","item":"https:\/\/www.muzard-sarl.com\/boutique-en-ligne-materiaux-metier-dart\/"},{"@type":"ListItem","position":3,"name":"Plaquettes et carrelets en Bois","item":"https:\/\/www.muzard-sarl.com\/categorie-produit\/plaquettes-et-carrelets-en-bois\/"},{"@type":"ListItem","position":4,"name":"Plaquettes en Loupe de Bois de Cade Qualit\u00e9++"}]},{"@type":"WebSite","@id":"https:\/\/www.muzard-sarl.com\/#website","url":"https:\/\/www.muzard-sarl.com\/","name":"Muzard SARL","description":"Manufacturer of wooden objects and horns since 1990","publisher":{"@id":"https:\/\/www.muzard-sarl.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.muzard-sarl.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.muzard-sarl.com\/#organization","name":"MUZARD SARL","url":"https:\/\/www.muzard-sarl.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png","contentUrl":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png","width":1916,"height":413,"caption":"MUZARD SARL"},"image":{"@id":"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/muzardSarl\/","https:\/\/www.instagram.com\/muzard_sarl\/?hl=fr"]}]}},"_links":{"self":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/product\/11074"}],"collection":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/comments?post=11074"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/media\/11535"}],"wp:attachment":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/media?parent=11074"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/product_cat?post=11074"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/product_tag?post=11074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}