{"id":3420,"date":"2022-12-08T10:13:57","date_gmt":"2022-12-08T09:13:57","guid":{"rendered":"https:\/\/www.muzard-sarl.com\/?post_type=product&#038;p=3420"},"modified":"2026-04-08T13:30:57","modified_gmt":"2026-04-08T11:30:57","slug":"plaquettes-pointe-de-zebu-art-couteau-manche-naturel","status":"publish","type":"product","link":"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/","title":{"rendered":"Plaquettes pointe de Z\u00e9bu"},"content":{"rendered":"<p>Paire de plaquettes en pointe de corne jasp\u00e9e<\/p>\n<p><em><strong>Qualit\u00e9 exceptionnelle<\/strong><\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Pointe de corne jasp\u00e9e<\/p>\n<p><em>Dimensions : 135 x 35 x 7 mm<\/em><\/p>","protected":false},"featured_media":14918,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[]},"product_cat":[123],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plaquettes pointe de Z\u00e9bu - Muzard SARL<\/title>\n<meta name=\"description\" content=\"Plaquettes pointe de Z\u00e9bu - Muzard SARL Paire de plaquettes en pointe de corne de z\u00e9bu, id\u00e9al pour vos r\u00e9alisations uniques.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plaquettes pointe de Z\u00e9bu - Muzard SARL\" \/>\n<meta property=\"og:description\" content=\"Plaquettes pointe de Z\u00e9bu - Muzard SARL Paire de plaquettes en pointe de corne de z\u00e9bu, id\u00e9al pour vos r\u00e9alisations uniques.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/\" \/>\n<meta property=\"og:site_name\" content=\"Muzard SARL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/muzardSarl\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T11:30:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/12\/plaquette-ZEBU-coutellerie-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/\",\"url\":\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/\",\"name\":\"Plaquettes pointe de Z\u00e9bu - Muzard SARL\",\"isPartOf\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#website\"},\"datePublished\":\"2022-12-08T09:13:57+00:00\",\"dateModified\":\"2026-04-08T11:30:57+00:00\",\"description\":\"Plaquettes pointe de Z\u00e9bu - Muzard SARL Paire de plaquettes en pointe de corne de z\u00e9bu, id\u00e9al pour vos r\u00e9alisations uniques.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.muzard-sarl.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique Mat\u00e9riaux de Coutellerie\",\"item\":\"https:\/\/www.muzard-sarl.com\/boutique-en-ligne-materiaux-metier-dart\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plaquettes en corne v\u00e9ritable\",\"item\":\"https:\/\/www.muzard-sarl.com\/categorie-produit\/plaquettes-en-corne-veritable\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Pointe de corne de Z\u00e9bu\",\"item\":\"https:\/\/www.muzard-sarl.com\/categorie-produit\/plaquettes-en-corne-veritable\/zebu\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Plaquettes pointe de Z\u00e9bu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#website\",\"url\":\"https:\/\/www.muzard-sarl.com\/\",\"name\":\"Muzard SARL\",\"description\":\"Fabricant d&#039;objets en bois et corne depuis 1990\",\"publisher\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.muzard-sarl.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#organization\",\"name\":\"MUZARD SARL\",\"url\":\"https:\/\/www.muzard-sarl.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png\",\"contentUrl\":\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png\",\"width\":1916,\"height\":413,\"caption\":\"MUZARD SARL\"},\"image\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/muzardSarl\/\",\"https:\/\/www.instagram.com\/muzard_sarl\/?hl=fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plaquettes pointe de Z\u00e9bu - Muzard SARL","description":"Plaquettes pointe de Z\u00e9bu - Muzard SARL Paire de plaquettes en pointe de corne de z\u00e9bu, id\u00e9al pour vos r\u00e9alisations uniques.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/","og_locale":"en_GB","og_type":"article","og_title":"Plaquettes pointe de Z\u00e9bu - Muzard SARL","og_description":"Plaquettes pointe de Z\u00e9bu - Muzard SARL Paire de plaquettes en pointe de corne de z\u00e9bu, id\u00e9al pour vos r\u00e9alisations uniques.","og_url":"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/","og_site_name":"Muzard SARL","article_publisher":"https:\/\/www.facebook.com\/muzardSarl\/","article_modified_time":"2026-04-08T11:30:57+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/12\/plaquette-ZEBU-coutellerie-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/","url":"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/","name":"Plaquettes pointe de Z\u00e9bu - Muzard SARL","isPartOf":{"@id":"https:\/\/www.muzard-sarl.com\/#website"},"datePublished":"2022-12-08T09:13:57+00:00","dateModified":"2026-04-08T11:30:57+00:00","description":"Plaquettes pointe de Z\u00e9bu - Muzard SARL Paire de plaquettes en pointe de corne de z\u00e9bu, id\u00e9al pour vos r\u00e9alisations uniques.","breadcrumb":{"@id":"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.muzard-sarl.com\/produit\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-pointe-de-zebu-art-couteau-manche-naturel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.muzard-sarl.com\/"},{"@type":"ListItem","position":2,"name":"Boutique Mat\u00e9riaux de Coutellerie","item":"https:\/\/www.muzard-sarl.com\/boutique-en-ligne-materiaux-metier-dart\/"},{"@type":"ListItem","position":3,"name":"Plaquettes en corne v\u00e9ritable","item":"https:\/\/www.muzard-sarl.com\/categorie-produit\/plaquettes-en-corne-veritable\/"},{"@type":"ListItem","position":4,"name":"Pointe de corne de Z\u00e9bu","item":"https:\/\/www.muzard-sarl.com\/categorie-produit\/plaquettes-en-corne-veritable\/zebu\/"},{"@type":"ListItem","position":5,"name":"Plaquettes pointe de Z\u00e9bu"}]},{"@type":"WebSite","@id":"https:\/\/www.muzard-sarl.com\/#website","url":"https:\/\/www.muzard-sarl.com\/","name":"Muzard SARL","description":"Manufacturer of wooden objects and horns since 1990","publisher":{"@id":"https:\/\/www.muzard-sarl.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.muzard-sarl.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.muzard-sarl.com\/#organization","name":"MUZARD SARL","url":"https:\/\/www.muzard-sarl.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png","contentUrl":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png","width":1916,"height":413,"caption":"MUZARD SARL"},"image":{"@id":"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/muzardSarl\/","https:\/\/www.instagram.com\/muzard_sarl\/?hl=fr"]}]}},"_links":{"self":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/product\/3420"}],"collection":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/comments?post=3420"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/media\/14918"}],"wp:attachment":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/media?parent=3420"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/product_cat?post=3420"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/product_tag?post=3420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}