{"id":4232,"date":"2023-02-10T11:08:45","date_gmt":"2023-02-10T10:08:45","guid":{"rendered":"https:\/\/www.muzard-sarl.com\/?post_type=product&#038;p=4232"},"modified":"2025-12-16T14:50:32","modified_gmt":"2025-12-16T13:50:32","slug":"plaquettes-ebene-royal-12","status":"publish","type":"product","link":"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-ebene-royal-12\/","title":{"rendered":"Plaquettes Eb\u00e8ne Royal"},"content":{"rendered":"<p>Plaquettes en <strong>Eb\u00e8ne royal<\/strong> <strong>135x35x7mm<\/strong><\/p>\n<p>Paire de plaquettes en Eb\u00e8ne du Laos. Bois provenant du Laos. Les reflets blancs et noirs font de lui un de bois les plus pr\u00e9cieux au monde.<\/p>","protected":false},"excerpt":{"rendered":"<p>Dimensions : 135 x 35 x 7 mm<\/p>","protected":false},"featured_media":13916,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_vp_format_video_url":"","_vp_image_focal_point":[]},"product_cat":[43,93,486],"product_tag":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.13 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plaquettes Eb\u00e8ne Royal - Muzard SARL<\/title>\n<meta name=\"description\" content=\"Paire de plaquettes en Eb\u00e8ne du Laos. Bois provenant du Laos. Les reflets blancs et noirs font de lui un de bois les plus pr\u00e9cieux au monde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-ebene-royal-12\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plaquettes Eb\u00e8ne Royal - Muzard SARL\" \/>\n<meta property=\"og:description\" content=\"Paire de plaquettes en Eb\u00e8ne du Laos. Bois provenant du Laos. Les reflets blancs et noirs font de lui un de bois les plus pr\u00e9cieux au monde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-ebene-royal-12\/\" \/>\n<meta property=\"og:site_name\" content=\"Muzard SARL\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/muzardSarl\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-16T13:50:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2023\/02\/plaquettes-couteaux-ebene-royal-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-ebene-royal-12\/\",\"url\":\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-ebene-royal-12\/\",\"name\":\"Plaquettes Eb\u00e8ne Royal - Muzard SARL\",\"isPartOf\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#website\"},\"datePublished\":\"2023-02-10T10:08:45+00:00\",\"dateModified\":\"2025-12-16T13:50:32+00:00\",\"description\":\"Paire de plaquettes en Eb\u00e8ne du Laos. Bois provenant du Laos. Les reflets blancs et noirs font de lui un de bois les plus pr\u00e9cieux au monde.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-ebene-royal-12\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-ebene-royal-12\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-ebene-royal-12\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.muzard-sarl.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boutique Mat\u00e9riaux de Coutellerie\",\"item\":\"https:\/\/www.muzard-sarl.com\/boutique-en-ligne-materiaux-metier-dart\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Plaquettes et carrelets en Bois\",\"item\":\"https:\/\/www.muzard-sarl.com\/categorie-produit\/plaquettes-et-carrelets-en-bois\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Plaquettes Eb\u00e8ne Royal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#website\",\"url\":\"https:\/\/www.muzard-sarl.com\/\",\"name\":\"Muzard SARL\",\"description\":\"Fabricant d&#039;objets en bois et corne depuis 1990\",\"publisher\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.muzard-sarl.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#organization\",\"name\":\"MUZARD SARL\",\"url\":\"https:\/\/www.muzard-sarl.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png\",\"contentUrl\":\"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png\",\"width\":1916,\"height\":413,\"caption\":\"MUZARD SARL\"},\"image\":{\"@id\":\"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/muzardSarl\/\",\"https:\/\/www.instagram.com\/muzard_sarl\/?hl=fr\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plaquettes Eb\u00e8ne Royal - Muzard SARL","description":"Paire de plaquettes en Eb\u00e8ne du Laos. Bois provenant du Laos. Les reflets blancs et noirs font de lui un de bois les plus pr\u00e9cieux au monde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-ebene-royal-12\/","og_locale":"en_GB","og_type":"article","og_title":"Plaquettes Eb\u00e8ne Royal - Muzard SARL","og_description":"Paire de plaquettes en Eb\u00e8ne du Laos. Bois provenant du Laos. Les reflets blancs et noirs font de lui un de bois les plus pr\u00e9cieux au monde.","og_url":"https:\/\/www.muzard-sarl.com\/en\/product\/plaquettes-ebene-royal-12\/","og_site_name":"Muzard SARL","article_publisher":"https:\/\/www.facebook.com\/muzardSarl\/","article_modified_time":"2025-12-16T13:50:32+00:00","og_image":[{"width":1000,"height":1000,"url":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2023\/02\/plaquettes-couteaux-ebene-royal-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Estimated reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-ebene-royal-12\/","url":"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-ebene-royal-12\/","name":"Plaquettes Eb\u00e8ne Royal - Muzard SARL","isPartOf":{"@id":"https:\/\/www.muzard-sarl.com\/#website"},"datePublished":"2023-02-10T10:08:45+00:00","dateModified":"2025-12-16T13:50:32+00:00","description":"Paire de plaquettes en Eb\u00e8ne du Laos. Bois provenant du Laos. Les reflets blancs et noirs font de lui un de bois les plus pr\u00e9cieux au monde.","breadcrumb":{"@id":"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-ebene-royal-12\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.muzard-sarl.com\/produit\/plaquettes-ebene-royal-12\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.muzard-sarl.com\/produit\/plaquettes-ebene-royal-12\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.muzard-sarl.com\/"},{"@type":"ListItem","position":2,"name":"Boutique Mat\u00e9riaux de Coutellerie","item":"https:\/\/www.muzard-sarl.com\/boutique-en-ligne-materiaux-metier-dart\/"},{"@type":"ListItem","position":3,"name":"Plaquettes et carrelets en Bois","item":"https:\/\/www.muzard-sarl.com\/categorie-produit\/plaquettes-et-carrelets-en-bois\/"},{"@type":"ListItem","position":4,"name":"Plaquettes Eb\u00e8ne Royal"}]},{"@type":"WebSite","@id":"https:\/\/www.muzard-sarl.com\/#website","url":"https:\/\/www.muzard-sarl.com\/","name":"Muzard SARL","description":"Manufacturer of wooden objects and horns since 1990","publisher":{"@id":"https:\/\/www.muzard-sarl.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.muzard-sarl.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.muzard-sarl.com\/#organization","name":"MUZARD SARL","url":"https:\/\/www.muzard-sarl.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png","contentUrl":"https:\/\/www.muzard-sarl.com\/wp-content\/uploads\/2022\/04\/cropped-cropped-Logo-Muzard-SARL-Site-Muzard-ok.png","width":1916,"height":413,"caption":"MUZARD SARL"},"image":{"@id":"https:\/\/www.muzard-sarl.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/muzardSarl\/","https:\/\/www.instagram.com\/muzard_sarl\/?hl=fr"]}]}},"_links":{"self":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/product\/4232"}],"collection":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/comments?post=4232"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/media\/13916"}],"wp:attachment":[{"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/media?parent=4232"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/product_cat?post=4232"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.muzard-sarl.com\/en\/wp-json\/wp\/v2\/product_tag?post=4232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}